{"id":13155,"date":"2026-05-07T09:14:07","date_gmt":"2026-05-07T16:14:07","guid":{"rendered":"https:\/\/foromdc.org\/?post_type=carbono_neutral&#038;p=13155"},"modified":"2026-05-28T11:45:00","modified_gmt":"2026-05-28T18:45:00","slug":"una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental","status":"publish","type":"carbono_neutral","link":"https:\/\/foromdc.org\/en\/carbono_neutral\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\/","title":{"rendered":"Una cient\u00edfica sinaloense busca transformar el cemento para reducir su huella ambiental"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"13155\" class=\"elementor elementor-13155\" data-elementor-post-type=\"carbono_neutral\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-179b190 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"179b190\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4238044\" data-id=\"4238044\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54fcd05 elementor-widget elementor-widget-text-editor\" data-id=\"54fcd05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The <strong>cement<\/strong> est\u00e1 en casi todo: viviendas, carreteras, puentes. Pero detr\u00e1s de su presencia cotidiana se esconde uno de los procesos industriales m\u00e1s contaminantes del mundo. Frente a ese desaf\u00edo, una investigaci\u00f3n desarrollada en <strong>Sinaloa<\/strong> plantea una alternativa que podr\u00eda cambiar la forma en que se construye.<\/p><p>Desde la Facultad de Ingenier\u00eda de la <strong>Autonomous University of Sinaloa<\/strong>, la cient\u00edfica <strong>Rub\u00ed Morales L\u00f3pez<\/strong> trabaja en el desarrollo de <strong>cementos h\u00edbridos alcalinos<\/strong>, una opci\u00f3n que busca reducir de manera significativa las <strong>emissions<\/strong> asociadas a este material clave en la infraestructura moderna.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4cc71f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4cc71f0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e01cce1\" data-id=\"e01cce1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3732e9a elementor-widget elementor-widget-image\" data-id=\"3732e9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.20-PM-1-1024x682.jpeg\" class=\"attachment-large size-large wp-image-13150\" alt=\"\" srcset=\"https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.20-PM-1-1024x682.jpeg 1024w, https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.20-PM-1-300x200.jpeg 300w, https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.20-PM-1-768x512.jpeg 768w, https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.20-PM-1-391x260.jpeg 391w, https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.20-PM-1-1536x1023.jpeg 1536w, https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.20-PM-1-18x12.jpeg 18w, https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.20-PM-1.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f2f9d65 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f2f9d65\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a3864c3\" data-id=\"a3864c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5a6302 elementor-widget elementor-widget-text-editor\" data-id=\"c5a6302\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Repensar el coraz\u00f3n del cemento<\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7259248 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7259248\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ea6c90b\" data-id=\"ea6c90b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29801f1 elementor-widget elementor-widget-text-editor\" data-id=\"29801f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El problema se concentra en el <strong>clinker<\/strong>, el componente principal del<strong> cemento convencional<\/strong>. Su producci\u00f3n exige temperaturas cercanas a los mil 500 grados cent\u00edgrados, lo que implica un <strong>high energy consumption<\/strong> y la liberaci\u00f3n de grandes cantidades de <strong>carbon dioxide<\/strong>.<\/p><p>La propuesta de Morales L\u00f3pez apunta a sustituir hasta el 70% de este material por alternativas de menor impacto.<\/p><blockquote><p><span style=\"color: #ff6600;\"><em>\u201cYo he estado trabajando con los cementos h\u00edbridos alcalinos desde mi maestr\u00eda, que fue mi proyecto de investigaci\u00f3n y con estos cementos se busca una sustituci\u00f3n de hasta un 70 por ciento del cemento Portland ordinario, o sea, del clinker. Esto para poder combatir el gran impacto ambiental que genera el cemento tradicional\u201d, explic\u00f3.<\/em><\/span><\/p><\/blockquote><p>Entre los materiales utilizados destaca el <strong>metacaol\u00edn<\/strong>, obtenido a partir de arcillas y procesado a temperaturas considerablemente m\u00e1s bajas.<\/p><blockquote><p><em><span style=\"color: #ff6600;\">\u201cCompar\u00e1ndolo, las temperaturas disminuyen, son menores y los tiempos tambi\u00e9n\u201d, detall\u00f3, al subrayar las ventajas energ\u00e9ticas de esta alternativa.<\/span><\/em><\/p><\/blockquote><p>Este cambio no solo representa una mejora t\u00e9cnica, sino una oportunidad para reducir la <strong>environmental footprint<\/strong> de toda la industria de la construcci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ea74ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ea74ef\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-baa512e\" data-id=\"baa512e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d40727 elementor-widget elementor-widget-image\" data-id=\"4d40727\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.17-PM-1024x682.jpeg\" class=\"attachment-large size-large wp-image-13151\" alt=\"\" srcset=\"https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.17-PM-1024x682.jpeg 1024w, https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.17-PM-300x200.jpeg 300w, https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.17-PM-768x512.jpeg 768w, https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.17-PM-391x260.jpeg 391w, https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.17-PM-1536x1023.jpeg 1536w, https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.17-PM-18x12.jpeg 18w, https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.17-PM.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d3751aa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3751aa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d51cc83\" data-id=\"d51cc83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-870b16c elementor-widget elementor-widget-text-editor\" data-id=\"870b16c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Innovaci\u00f3n con ra\u00edces locales<\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f2d170 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f2d170\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e4b92bd\" data-id=\"e4b92bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b499f9 elementor-widget elementor-widget-text-editor\" data-id=\"8b499f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El proyecto tambi\u00e9n pone el acento en el territorio. La incorporaci\u00f3n de materiales disponibles en <strong>Sinaloa<\/strong>as the <strong>zeolita<\/strong>, abre la posibilidad de desarrollar <strong>soluciones m\u00e1s sostenibles<\/strong> a partir de recursos regionales.<\/p><p>Adem\u00e1s de mejorar el desempe\u00f1o del<strong> cement<\/strong>, este enfoque fortalece una l\u00f3gica de innovaci\u00f3n que conecta la ciencia con el entorno, reduciendo la dependencia de insumos externos y promoviendo el aprovechamiento responsable de los recursos locales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8c0dfc0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8c0dfc0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-07130a6\" data-id=\"07130a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eedd8d0 elementor-widget elementor-widget-text-editor\" data-id=\"eedd8d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong>Un futuro a\u00fan en pruebas<\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cdde18a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cdde18a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-535ff5d\" data-id=\"535ff5d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-646a700 elementor-widget elementor-widget-text-editor\" data-id=\"646a700\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aunque los resultados son prometedores, la investigaci\u00f3n se encuentra en etapa experimental. Actualmente, se realizan pruebas de durabilidad para comparar el desempe\u00f1o de los <strong>cementos h\u00edbridos<\/strong> frente a los tradicionales, un paso clave antes de pensar en su aplicaci\u00f3n a mayor escala.<\/p><blockquote><p><span style=\"color: #ff6600;\"><em>\u201cActualmente en la etapa que estamos es de investigaci\u00f3n. Se est\u00e1n agregando estas pruebas de durabilidad de los cementos h\u00edbridos compar\u00e1ndolos con los tradicionales, siempre teniendo esta comparaci\u00f3n de los tradicionales con los h\u00edbridos\u201d, se\u00f1al\u00f3.<\/em><\/span><\/p><\/blockquote><p>Por este trabajo, Morales L\u00f3pez fue reconocida en 2025 con el <strong>Premio Eustaquio Buelna<\/strong> to the <strong>Mejor Tesis de Posgrad<\/strong>o, un reconocimiento que destaca el potencial de su propuesta.<\/p><p>M\u00e1s all\u00e1 del laboratorio, su investigaci\u00f3n plantea una ruta posible para una industria que enfrenta presiones crecientes por reducir su<strong> environmental impact<\/strong>. En esa transici\u00f3n, repensar el <strong>cement<\/strong> podr\u00eda ser uno de los primeros pasos para construir ciudades m\u00e1s sostenibles.<\/p><p>Source: <a href=\"https:\/\/www.ccs.edu.mx\/Nota\/post\/61?fbclid=IwY2xjawRpmUdleHRuA2FlbQIxMABicmlkETFQQjlQc1lPcnVsTFhLa1dHc3J0YwZhcHBfaWQQMjIyMDM5MTc4ODIwMDg5MgABHlofVg48j3zcfgd512sJtb_4g1wVRn_dNuZqjdrttduFP0TxhBP9_hkaRa-5_aem_NVAdmqXKYxpWOwn6w8JOEg\">CONFIE<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Desde la UAS, una investigaci\u00f3n de Rub\u00ed Morales propone sustituir hasta 70% del cemento tradicional con materiales de menor impacto y origen local<\/p>","protected":false},"featured_media":13152,"template":"","categories":[],"tags":[788,790,283,789],"class_list":["post-13155","carbono_neutral","type-carbono_neutral","status-publish","has-post-thumbnail","hentry","tag-cemento-ecologico","tag-huella-ambiental","tag-sinaloa","tag-uas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una cient\u00edfica sinaloense busca transformar el cemento para reducir su huella ambiental - Foro Mar de Cort\u00e9s<\/title>\n<meta name=\"description\" content=\"Desde la UAS, una investigaci\u00f3n de Rub\u00ed Morales propone sustituir hasta 70% del cemento tradicional con materiales de menor impacto y origen local\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foromdc.org\/en\/carbono_neutral\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una cient\u00edfica sinaloense busca transformar el cemento para reducir su huella ambiental - Foro Mar de Cort\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Desde la UAS, una investigaci\u00f3n de Rub\u00ed Morales propone sustituir hasta 70% del cemento tradicional con materiales de menor impacto y origen local\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foromdc.org\/en\/carbono_neutral\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\/\" \/>\n<meta property=\"og:site_name\" content=\"Foro Mar de Cort\u00e9s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Foro-Mar-de-Corts-102782702603939\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-28T18:45:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.23-PM-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/foromdc.org\\\/carbono_neutral\\\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\\\/\",\"url\":\"https:\\\/\\\/foromdc.org\\\/carbono_neutral\\\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\\\/\",\"name\":\"Una cient\u00edfica sinaloense busca transformar el cemento para reducir su huella ambiental - Foro Mar de Cort\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/foromdc.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/foromdc.org\\\/carbono_neutral\\\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/foromdc.org\\\/carbono_neutral\\\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/foromdc.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-23-at-12.31.23-PM-1.jpg\",\"datePublished\":\"2026-05-07T16:14:07+00:00\",\"dateModified\":\"2026-05-28T18:45:00+00:00\",\"description\":\"Desde la UAS, una investigaci\u00f3n de Rub\u00ed Morales propone sustituir hasta 70% del cemento tradicional con materiales de menor impacto y origen local\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/foromdc.org\\\/carbono_neutral\\\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/foromdc.org\\\/carbono_neutral\\\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/foromdc.org\\\/carbono_neutral\\\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\\\/#primaryimage\",\"url\":\"https:\\\/\\\/foromdc.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-23-at-12.31.23-PM-1.jpg\",\"contentUrl\":\"https:\\\/\\\/foromdc.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-23-at-12.31.23-PM-1.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Una cient\u00edfica sinaloense busca transformar el cemento para reducir su huella ambiental,\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/foromdc.org\\\/carbono_neutral\\\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/foromdc.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carbono Neutral\",\"item\":\"https:\\\/\\\/foromdc.org\\\/carbono_neutral\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Una cient\u00edfica sinaloense busca transformar el cemento para reducir su huella ambiental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/foromdc.org\\\/#website\",\"url\":\"https:\\\/\\\/foromdc.org\\\/\",\"name\":\"Foro Mar de Cort\u00e9s\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/foromdc.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/foromdc.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/foromdc.org\\\/#organization\",\"name\":\"Foro Mar de Cort\u00e9s\",\"url\":\"https:\\\/\\\/foromdc.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/foromdc.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/foromdc.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cropped-Logo.png\",\"contentUrl\":\"https:\\\/\\\/foromdc.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/cropped-Logo.png\",\"width\":386,\"height\":72,\"caption\":\"Foro Mar de Cort\u00e9s\"},\"image\":{\"@id\":\"https:\\\/\\\/foromdc.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Foro-Mar-de-Corts-102782702603939\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una cient\u00edfica sinaloense busca transformar el cemento para reducir su huella ambiental - Foro Mar de Cort\u00e9s","description":"Desde la UAS, una investigaci\u00f3n de Rub\u00ed Morales propone sustituir hasta 70% del cemento tradicional con materiales de menor impacto y origen local","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foromdc.org\/en\/carbono_neutral\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\/","og_locale":"en_US","og_type":"article","og_title":"Una cient\u00edfica sinaloense busca transformar el cemento para reducir su huella ambiental - Foro Mar de Cort\u00e9s","og_description":"Desde la UAS, una investigaci\u00f3n de Rub\u00ed Morales propone sustituir hasta 70% del cemento tradicional con materiales de menor impacto y origen local","og_url":"https:\/\/foromdc.org\/en\/carbono_neutral\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\/","og_site_name":"Foro Mar de Cort\u00e9s","article_publisher":"https:\/\/www.facebook.com\/Foro-Mar-de-Corts-102782702603939","article_modified_time":"2026-05-28T18:45:00+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.23-PM-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/foromdc.org\/carbono_neutral\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\/","url":"https:\/\/foromdc.org\/carbono_neutral\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\/","name":"Una cient\u00edfica sinaloense busca transformar el cemento para reducir su huella ambiental - Foro Mar de Cort\u00e9s","isPartOf":{"@id":"https:\/\/foromdc.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foromdc.org\/carbono_neutral\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\/#primaryimage"},"image":{"@id":"https:\/\/foromdc.org\/carbono_neutral\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\/#primaryimage"},"thumbnailUrl":"https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.23-PM-1.jpg","datePublished":"2026-05-07T16:14:07+00:00","dateModified":"2026-05-28T18:45:00+00:00","description":"Desde la UAS, una investigaci\u00f3n de Rub\u00ed Morales propone sustituir hasta 70% del cemento tradicional con materiales de menor impacto y origen local","breadcrumb":{"@id":"https:\/\/foromdc.org\/carbono_neutral\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foromdc.org\/carbono_neutral\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/foromdc.org\/carbono_neutral\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\/#primaryimage","url":"https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.23-PM-1.jpg","contentUrl":"https:\/\/foromdc.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-23-at-12.31.23-PM-1.jpg","width":1200,"height":800,"caption":"Una cient\u00edfica sinaloense busca transformar el cemento para reducir su huella ambiental,"},{"@type":"BreadcrumbList","@id":"https:\/\/foromdc.org\/carbono_neutral\/una-cientifica-sinaloense-busca-transformar-el-cemento-para-reducir-su-huella-ambiental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/foromdc.org\/"},{"@type":"ListItem","position":2,"name":"Carbono Neutral","item":"https:\/\/foromdc.org\/carbono_neutral\/"},{"@type":"ListItem","position":3,"name":"Una cient\u00edfica sinaloense busca transformar el cemento para reducir su huella ambiental"}]},{"@type":"WebSite","@id":"https:\/\/foromdc.org\/#website","url":"https:\/\/foromdc.org\/","name":"Sea of Cortez Forum","description":"","publisher":{"@id":"https:\/\/foromdc.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foromdc.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/foromdc.org\/#organization","name":"Sea of Cortez Forum","url":"https:\/\/foromdc.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/foromdc.org\/#\/schema\/logo\/image\/","url":"https:\/\/foromdc.org\/wp-content\/uploads\/2021\/06\/cropped-Logo.png","contentUrl":"https:\/\/foromdc.org\/wp-content\/uploads\/2021\/06\/cropped-Logo.png","width":386,"height":72,"caption":"Foro Mar de Cort\u00e9s"},"image":{"@id":"https:\/\/foromdc.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Foro-Mar-de-Corts-102782702603939"]}]}},"_links":{"self":[{"href":"https:\/\/foromdc.org\/en\/wp-json\/wp\/v2\/carbono_neutral\/13155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foromdc.org\/en\/wp-json\/wp\/v2\/carbono_neutral"}],"about":[{"href":"https:\/\/foromdc.org\/en\/wp-json\/wp\/v2\/types\/carbono_neutral"}],"version-history":[{"count":7,"href":"https:\/\/foromdc.org\/en\/wp-json\/wp\/v2\/carbono_neutral\/13155\/revisions"}],"predecessor-version":[{"id":13162,"href":"https:\/\/foromdc.org\/en\/wp-json\/wp\/v2\/carbono_neutral\/13155\/revisions\/13162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foromdc.org\/en\/wp-json\/wp\/v2\/media\/13152"}],"wp:attachment":[{"href":"https:\/\/foromdc.org\/en\/wp-json\/wp\/v2\/media?parent=13155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foromdc.org\/en\/wp-json\/wp\/v2\/categories?post=13155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foromdc.org\/en\/wp-json\/wp\/v2\/tags?post=13155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}